{"id":237,"count":26,"description":"Bachbl\u00fcten sind nat\u00fcrliche Heilmittel, die in den 1930er Jahren von Dr. Edward Bach entwickelt wurden.\r\nSie bestehen aus Bl\u00fctenessenzen und werden verwendet, um emotionale und seelische Ungleichgewichte zu behandeln.\r\nDr. Bach entwickelte 38 verschiedene Essenzen \u2013 jede f\u00fcr einen bestimmten Gem\u00fctszustand.\r\nDie Therapie basiert auf der Idee, dass negative Gef\u00fchle durch positive ersetzt werden k\u00f6nnen.\r\nBachbl\u00fcten sind im Allgemeinen sicher, verursachen keine Nebenwirkungen und k\u00f6nnen mit anderen Therapien kombiniert werden.\r\nWir bieten individuell abgestimmte Bachbl\u00fctenmischungen an, zubereitet von zertifizierten Bach-Beratern.\r\nGeeignet f\u00fcr alle \u2013 einschlie\u00dflich Schwangere, Kinder, \u00e4ltere Menschen und sogar Tiere.\r\nKeine Nebenwirkungen, keine \u00dcberdosierung, keine Abh\u00e4ngigkeit.\r\n\r\nEntdecken Sie alle unsere Produkte und ihre Vorteile.","link":"https:\/\/fengchashop.com\/de\/product-category\/bachblueten\/","name":"Bachbl\u00fcten","slug":"bachblueten","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/fengchashop.com\/de\/wp-json\/wp\/v2\/product_cat\/237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fengchashop.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/fengchashop.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/fengchashop.com\/de\/wp-json\/wp\/v2\/product?product_cat=237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}